{"id":7220,"date":"2017-01-07T16:50:00","date_gmt":"2017-01-07T14:50:00","guid":{"rendered":"http:\/\/www.deacapitalre.com\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/"},"modified":"2020-12-09T17:26:13","modified_gmt":"2020-12-09T15:26:13","slug":"ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only","status":"publish","type":"post","link":"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/","title":{"rendered":"ANSA 7 gennaio 2017 &#8211; IDeA FIMIT precisa in merito a Fondo Alpha (ita only)"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":4335,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[182],"tags":[],"class_list":["post-7220","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-media"],"acf":[],"yoast_head":"\n<title>ANSA 7 gennaio 2017 - IDeA FIMIT precisa in merito a Fondo Alpha (ita only) - DeA Capital Real Estate SGR<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ANSA 7 gennaio 2017 - IDeA FIMIT precisa in merito a Fondo Alpha (ita only) - DeA Capital Real Estate SGR\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/\" \/>\n<meta property=\"og:site_name\" content=\"DeA Capital Real Estate SGR\" \/>\n<meta property=\"article:published_time\" content=\"2017-01-07T14:50:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-12-09T15:26:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/deagostini-prod-deacapitalre.s3.eu-west-1.amazonaws.com\/wp-content\/uploads\/2020\/07\/10182316\/News-placeholder.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\/\/www.deacapitalre.com\/#\/schema\/person\/5ce386026b588c784b9bacea2d179622\"},\"headline\":\"ANSA 7 gennaio 2017 &#8211; IDeA FIMIT precisa in merito a Fondo Alpha (ita only)\",\"datePublished\":\"2017-01-07T14:50:00+00:00\",\"dateModified\":\"2020-12-09T15:26:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/\"},\"wordCount\":13,\"image\":{\"@id\":\"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.deacapitalre.com\/wp-content\/uploads\/2020\/07\/News-placeholder.jpg\",\"articleSection\":[\"Media\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/\",\"url\":\"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/\",\"name\":\"ANSA 7 gennaio 2017 - IDeA FIMIT precisa in merito a Fondo Alpha (ita only) - DeA Capital Real Estate SGR\",\"isPartOf\":{\"@id\":\"https:\/\/www.deacapitalre.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.deacapitalre.com\/wp-content\/uploads\/2020\/07\/News-placeholder.jpg\",\"datePublished\":\"2017-01-07T14:50:00+00:00\",\"dateModified\":\"2020-12-09T15:26:13+00:00\",\"author\":{\"@id\":\"https:\/\/www.deacapitalre.com\/#\/schema\/person\/5ce386026b588c784b9bacea2d179622\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/#primaryimage\",\"url\":\"https:\/\/www.deacapitalre.com\/wp-content\/uploads\/2020\/07\/News-placeholder.jpg\",\"contentUrl\":\"https:\/\/www.deacapitalre.com\/wp-content\/uploads\/2020\/07\/News-placeholder.jpg\",\"width\":720,\"height\":440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.deacapitalre.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"ANSA 7 gennaio 2017 &#8211; IDeA FIMIT precisa in merito a Fondo Alpha (ita only)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.deacapitalre.com\/#website\",\"url\":\"https:\/\/www.deacapitalre.com\/\",\"name\":\"DeA Capital Real Estate SGR\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.deacapitalre.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.deacapitalre.com\/#\/schema\/person\/5ce386026b588c784b9bacea2d179622\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.deacapitalre.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/798cd18bfe23a14155980ca92abe854ec799b455e71551d5bf8f869c296f599f?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/798cd18bfe23a14155980ca92abe854ec799b455e71551d5bf8f869c296f599f?s=96&d=mm&r=g\",\"caption\":\"admin\"}}]}<\/script>\n","yoast_head_json":{"title":"ANSA 7 gennaio 2017 - IDeA FIMIT precisa in merito a Fondo Alpha (ita only) - DeA Capital Real Estate SGR","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/","og_locale":"en_US","og_type":"article","og_title":"ANSA 7 gennaio 2017 - IDeA FIMIT precisa in merito a Fondo Alpha (ita only) - DeA Capital Real Estate SGR","og_url":"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/","og_site_name":"DeA Capital Real Estate SGR","article_published_time":"2017-01-07T14:50:00+00:00","article_modified_time":"2020-12-09T15:26:13+00:00","og_image":[{"width":720,"height":440,"url":"https:\/\/deagostini-prod-deacapitalre.s3.eu-west-1.amazonaws.com\/wp-content\/uploads\/2020\/07\/10182316\/News-placeholder.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/#article","isPartOf":{"@id":"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/"},"author":{"name":"admin","@id":"https:\/\/www.deacapitalre.com\/#\/schema\/person\/5ce386026b588c784b9bacea2d179622"},"headline":"ANSA 7 gennaio 2017 &#8211; IDeA FIMIT precisa in merito a Fondo Alpha (ita only)","datePublished":"2017-01-07T14:50:00+00:00","dateModified":"2020-12-09T15:26:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/"},"wordCount":13,"image":{"@id":"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deacapitalre.com\/wp-content\/uploads\/2020\/07\/News-placeholder.jpg","articleSection":["Media"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/","url":"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/","name":"ANSA 7 gennaio 2017 - IDeA FIMIT precisa in merito a Fondo Alpha (ita only) - DeA Capital Real Estate SGR","isPartOf":{"@id":"https:\/\/www.deacapitalre.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/#primaryimage"},"image":{"@id":"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/#primaryimage"},"thumbnailUrl":"https:\/\/www.deacapitalre.com\/wp-content\/uploads\/2020\/07\/News-placeholder.jpg","datePublished":"2017-01-07T14:50:00+00:00","dateModified":"2020-12-09T15:26:13+00:00","author":{"@id":"https:\/\/www.deacapitalre.com\/#\/schema\/person\/5ce386026b588c784b9bacea2d179622"},"breadcrumb":{"@id":"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/#primaryimage","url":"https:\/\/www.deacapitalre.com\/wp-content\/uploads\/2020\/07\/News-placeholder.jpg","contentUrl":"https:\/\/www.deacapitalre.com\/wp-content\/uploads\/2020\/07\/News-placeholder.jpg","width":720,"height":440},{"@type":"BreadcrumbList","@id":"https:\/\/www.deacapitalre.com\/en\/ansa-7-gennaio-2017-idea-fimit-precisa-in-merito-a-fondo-alpha-ita-only\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.deacapitalre.com\/en\/"},{"@type":"ListItem","position":2,"name":"ANSA 7 gennaio 2017 &#8211; IDeA FIMIT precisa in merito a Fondo Alpha (ita only)"}]},{"@type":"WebSite","@id":"https:\/\/www.deacapitalre.com\/#website","url":"https:\/\/www.deacapitalre.com\/","name":"DeA Capital Real Estate SGR","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.deacapitalre.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.deacapitalre.com\/#\/schema\/person\/5ce386026b588c784b9bacea2d179622","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.deacapitalre.com\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/798cd18bfe23a14155980ca92abe854ec799b455e71551d5bf8f869c296f599f?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/798cd18bfe23a14155980ca92abe854ec799b455e71551d5bf8f869c296f599f?s=96&d=mm&r=g","caption":"admin"}}]}},"_links":{"self":[{"href":"https:\/\/www.deacapitalre.com\/en\/wp-json\/wp\/v2\/posts\/7220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.deacapitalre.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.deacapitalre.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.deacapitalre.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.deacapitalre.com\/en\/wp-json\/wp\/v2\/comments?post=7220"}],"version-history":[{"count":1,"href":"https:\/\/www.deacapitalre.com\/en\/wp-json\/wp\/v2\/posts\/7220\/revisions"}],"predecessor-version":[{"id":11801,"href":"https:\/\/www.deacapitalre.com\/en\/wp-json\/wp\/v2\/posts\/7220\/revisions\/11801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.deacapitalre.com\/en\/wp-json\/wp\/v2\/media\/4335"}],"wp:attachment":[{"href":"https:\/\/www.deacapitalre.com\/en\/wp-json\/wp\/v2\/media?parent=7220"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.deacapitalre.com\/en\/wp-json\/wp\/v2\/categories?post=7220"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.deacapitalre.com\/en\/wp-json\/wp\/v2\/tags?post=7220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}